{"id":430,"date":"2015-01-29T09:41:04","date_gmt":"2015-01-29T09:41:04","guid":{"rendered":"http:\/\/aletheme.com\/wordpress\/milagro\/?page_id=430"},"modified":"2015-01-29T09:41:04","modified_gmt":"2015-01-29T09:41:04","slug":"buttons-shortcode","status":"publish","type":"page","link":"http:\/\/wordpress.imholding.net\/theme8\/buttons-shortcode\/","title":{"rendered":"Buttons Shortcode"},"content":{"rendered":"<h3>Big rounded<\/h3>\n<a target=\"_self\" class=\"ale-button large grey round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large black round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large green round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large light-blue round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large blue round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large red round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large orange round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large purple round\" href=\"http:\/\/alethemes.com\"> Button <\/a>\n<p>Maecenas purus ipsum, cursus in tincidunt sed, fermentum a mi. Mauris pellentesque aliquet nibh, sit amet egestas orci tincidunt vel. Vivamus et ipsum ipsum. Etiam ultrices arcu sed volutpat facilisis. Morbi eget est molestie, tincidunt massa eget, facilisis justo<\/p>\n<h3>Big square<\/h3>\n<a target=\"_self\" class=\"ale-button large grey square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large black square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large green square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large light-blue square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large blue square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large red square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large orange square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button large purple square\" href=\"http:\/\/alethemes.com\"> Button <\/a>\n<p>Maecenas purus ipsum, cursus in tincidunt sed, fermentum a mi. Mauris pellentesque aliquet nibh, sit amet egestas orci tincidunt vel. Vivamus et ipsum ipsum. Etiam ultrices arcu sed volutpat facilisis. Morbi eget est molestie, tincidunt massa eget, facilisis justo<\/p>\n<h3>Middle rounded<\/h3>\n<a target=\"_self\" class=\"ale-button medium grey round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium black round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium green round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium light-blue round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium blue round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium red round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium orange round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium purple round\" href=\"http:\/\/alethemes.com\"> Button <\/a>\n<p>Maecenas purus ipsum, cursus in tincidunt sed, fermentum a mi. Mauris pellentesque aliquet nibh, sit amet egestas orci tincidunt vel. Vivamus et ipsum ipsum. Etiam ultrices arcu sed volutpat facilisis. Morbi eget est molestie, tincidunt massa eget, facilisis justo<\/p>\n<h3>Middle square<\/h3>\n<a target=\"_self\" class=\"ale-button medium grey square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium black square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium green square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium light-blue square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium blue square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium red square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium orange square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button medium purple square\" href=\"http:\/\/alethemes.com\"> Button <\/a>\n<p>Maecenas purus ipsum, cursus in tincidunt sed, fermentum a mi. Mauris pellentesque aliquet nibh, sit amet egestas orci tincidunt vel. Vivamus et ipsum ipsum. Etiam ultrices arcu sed volutpat facilisis. Morbi eget est molestie, tincidunt massa eget, facilisis justo<\/p>\n<h3>Small\u00a0rounded<\/h3>\n<a target=\"_self\" class=\"ale-button small grey round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small black round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small green round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small light-blue round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small blue round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small red round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small orange round\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small purple round\" href=\"http:\/\/alethemes.com\"> Button <\/a>\n<p>Maecenas purus ipsum, cursus in tincidunt sed, fermentum a mi. Mauris pellentesque aliquet nibh, sit amet egestas orci tincidunt vel. Vivamus et ipsum ipsum. Etiam ultrices arcu sed volutpat facilisis. Morbi eget est molestie, tincidunt massa eget, facilisis justo<\/p>\n<h3>Small square<\/h3>\n<a target=\"_self\" class=\"ale-button small grey square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small black square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small green square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small light-blue square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small blue square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small red square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small orange square\" href=\"http:\/\/alethemes.com\"> Button <\/a><a target=\"_self\" class=\"ale-button small purple square\" href=\"http:\/\/alethemes.com\"> Button <\/a>\n<p>Maecenas purus ipsum, cursus in tincidunt sed, fermentum a mi. Mauris pellentesque aliquet nibh, sit amet egestas orci tincidunt vel. Vivamus et ipsum ipsum. Etiam ultrices arcu sed volutpat facilisis. Morbi eget est molestie, tincidunt massa eget, facilisis justo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Big rounded Maecenas purus ipsum, cursus in tincidunt sed, fermentum a mi. Mauris pellentesque aliquet nibh, sit amet egestas orci tincidunt vel. Vivamus et ipsum ipsum. Etiam ultrices arcu sed volutpat facilisis. Morbi eget est molestie, tincidunt massa eget, facilisis justo Big square Maecenas purus ipsum, cursus in tincidunt sed, fermentum a mi. Mauris pellentesque [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-430","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/wordpress.imholding.net\/theme8\/wp-json\/wp\/v2\/pages\/430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wordpress.imholding.net\/theme8\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/wordpress.imholding.net\/theme8\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/wordpress.imholding.net\/theme8\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/wordpress.imholding.net\/theme8\/wp-json\/wp\/v2\/comments?post=430"}],"version-history":[{"count":0,"href":"http:\/\/wordpress.imholding.net\/theme8\/wp-json\/wp\/v2\/pages\/430\/revisions"}],"wp:attachment":[{"href":"http:\/\/wordpress.imholding.net\/theme8\/wp-json\/wp\/v2\/media?parent=430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}